{"id":202056,"date":"2025-12-28T17:33:58","date_gmt":"2025-12-28T20:33:58","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=202056"},"modified":"2025-12-28T17:33:58","modified_gmt":"2025-12-28T20:33:58","slug":"el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/","title":{"rendered":"El Gobierno prepara la segunda etapa de privatizaciones para 2026"},"content":{"rendered":"<p>Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei.<\/p>\n<p>El Gobierno se prepara para una nueva etapa de su plan de privatizaciones, con un cronograma que combina ingresos ya comprometidos, licitaciones en marcha y llamados previstos para el arranque de 2026. La prioridad oficial es doble: reducir el peso del Estado y favorecer el ingreso de divisas para las reservas del Banco Central.<\/p>\n<p>En los despachos oficiales subrayan que el proceso no se detendr\u00e1 y que constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n. La se\u00f1al se apoya en hechos recientes: el Ejecutivo se asegur\u00f3 US$700 millones por la reprivatizaci\u00f3n de cuatro represas hidroel\u00e9ctricas del Comahue, luego del desempate entre dos oferentes por Cerros Colorados. Ese dinero ayudar\u00e1 a programar pagos de comienzos de 2026.<\/p>\n<p>Econom\u00eda insiste en que todo d\u00f3lar que se sume a la econom\u00eda contar\u00e1, ya sea v\u00eda deuda en moneda extranjera, pr\u00e9stamos internacionales, exportaciones o ventas de activos. El mensaje busca mostrar que el plan para fortalecer reservas sigue en pie y se ejecutar\u00e1 cuando el contexto lo permita.<\/p>\n<p>Tras algunas demoras iniciales, el Gobierno apur\u00f3 el ritmo privatizador desde noviembre. Primero fue la ruta del Mercosur \u2014a trav\u00e9s de concesi\u00f3n\u2014 y luego llegaron las ofertas y la adjudicaci\u00f3n, el lunes 23, de las cuatro represas del Comahue.<\/p>\n<p>Privatizaciones: los pr\u00f3ximos pasos del Gobierno<\/p>\n<p>Ahora, en el final de a\u00f1o, el foco est\u00e1 puesto en los pr\u00f3ximos movimientos. Mientras espera que los fondos de las hidroel\u00e9ctricas engrosen las reservas del Bcra, el Gobierno abri\u00f3 el concurso para la venta de acciones que controlan Transener, la principal transportadora de energ\u00eda del pa\u00eds y un paso clave hacia la privatizaci\u00f3n de Enarsa. La apertura de sobres est\u00e1 prevista para el 23 de marzo.<\/p>\n<p>La agenda vial tambi\u00e9n avanza. En el tramo 2 -que incluye las autopistas Ricchieri; Ezeiza-Ca\u00f1uelas, as\u00ed como partes de la ruta 3 y la 5, entre los 1800 kil\u00f3metros a concesionar hoy operadas por Corredores Viales, el 6 de febrero se realizar\u00e1 la apertura de ofertas. Y en la hidrov\u00eda, ya se publicaron los pliegos para la reprivatizaci\u00f3n de la V\u00eda Navegable Troncal: el per\u00edodo de consultas est\u00e1 activo y la licitaci\u00f3n prev\u00e9 la apertura de sobres el 27 de febrero, con el objetivo oficial de que el proceso est\u00e9 listo para el inicio de la temporada alta de agroexportaciones.<\/p>\n<p>A esto se suma Intercargo, la empresa de servicios aeroportuarios. La intenci\u00f3n oficial es vender la totalidad del paquete accionario. En paralelo, AYSA figura para m\u00e1s adelante en los planes: se proyecta la venta del 90% de las acciones y, en el Gobierno, buscan que el proceso no se extienda m\u00e1s all\u00e1 de marzo de 2026, junto con una reducci\u00f3n de subsidios que permita hacerla atractiva para inversores.<\/p>\n<p>El frente ferroviario tambi\u00e9n tendr\u00e1 movimiento. En el caso de Belgrano Cargas, se espera para las primeras semanas del nuevo a\u00f1o la publicaci\u00f3n de los pliegos y un esquema en tres etapas: remate del material rodante, concesi\u00f3n de v\u00edas e inmuebles y concesi\u00f3n de talleres.<\/p>\n<p>El inter\u00e9s, seg\u00fan admiten en el sector, llega desde los principales exportadores de granos, de la miner\u00eda y de un operador mexicano que habl\u00f3 de posibles inversiones por US$3000 millones.<\/p>\n<p>Adem\u00e1s, el Ejecutivo puso en marcha un plan de obras en los trenes suburbanos para ponerlos en valor y hacerlos m\u00e1s atractivos a inversores en una futura privatizaci\u00f3n, por ahora sin fecha cierta.<\/p>\n<p>En el Gobierno afirman que los ingresos por estas operaciones ayudan a ordenar el frente fiscal y cambiario. Tambi\u00e9n remarcan que la prioridad es cumplir los pasos legales y sostener la competitividad de los activos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se prepara para una nueva etapa de su plan de privatizaciones, con un cronograma que combina ingresos ya comprometidos, licitaciones en marcha y llamados previstos para el arranque de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":202057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[29],"tags":[],"class_list":{"0":"post-202056","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno prepara la segunda etapa de privatizaciones para 2026 - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno prepara la segunda etapa de privatizaciones para 2026 - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-28T20:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"El Gobierno prepara la segunda etapa de privatizaciones para 2026\",\"datePublished\":\"2025-12-28T20:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\"},\"wordCount\":662,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\",\"name\":\"El Gobierno prepara la segunda etapa de privatizaciones para 2026 - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg\",\"datePublished\":\"2025-12-28T20:33:58+00:00\",\"description\":\"Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se\",\"breadcrumb\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg\",\"width\":680,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno prepara la segunda etapa de privatizaciones para 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\/\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno prepara la segunda etapa de privatizaciones para 2026 - Radio Infinita Goya","description":"Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno prepara la segunda etapa de privatizaciones para 2026 - Radio Infinita Goya","og_description":"Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2025-12-28T20:33:58+00:00","og_image":[{"width":680,"height":336,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg","type":"image\/jpeg"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"El Gobierno prepara la segunda etapa de privatizaciones para 2026","datePublished":"2025-12-28T20:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/"},"wordCount":662,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg","articleSection":["NACIONALES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/","name":"El Gobierno prepara la segunda etapa de privatizaciones para 2026 - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg","datePublished":"2025-12-28T20:33:58+00:00","description":"Desde el oficialismo se sostiene que esto constituye una de las fuentes de d\u00f3lares genuinos para la segunda parte de la gesti\u00f3n de Milei. El Gobierno se","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2025\/12\/G4S2utSWcAA16yM.jpg","width":680,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2025\/12\/28\/el-gobierno-prepara-la-segunda-etapa-de-privatizaciones-para-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"El Gobierno prepara la segunda etapa de privatizaciones para 2026"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/202056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=202056"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/202056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/202057"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=202056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=202056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=202056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}