{"id":204573,"date":"2026-02-10T16:28:44","date_gmt":"2026-02-10T19:28:44","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=204573"},"modified":"2026-02-10T16:28:44","modified_gmt":"2026-02-10T19:28:44","slug":"el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/","title":{"rendered":"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1"},"content":{"rendered":"<p>La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo<br \/>\nEl ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de volver a la M\u00e1xima<\/p>\n<p>El inter\u00e9s por una participaci\u00f3n en Alpine, el equipo que tiene como piloto titular al argentino Franco Colapinto atrajo a figuras destacadas de la F\u00f3rmula 1 e inversores institucionales, entre ellos al ex jefe todopoderoso de Red Bull Christian Horner, quien a mediados de 2025 fue despedido de la estructura luego de un conflicto interno que se hizo famoso dentro de la M\u00e1xima. La potencial operaci\u00f3n, que todav\u00eda es incierta y en negociaciones, podr\u00eda marcar un giro relevante para el futuro competitivo de la escuder\u00eda, dado su actual desempe\u00f1o y la valoraci\u00f3n creciente que experimentan los equipos de la categor\u00eda, sobre todo en v\u00edsperas de la nueva temporada con el cambio de reglamento t\u00e9cnico que podr\u00eda cambiar la lista de candidatos a pelear por los puntos en el campeonato.<\/p>\n<p>Fuentes citadas por Sky News, seg\u00fan el art\u00edculo que firm\u00f3 Mark Kleinman, estimaron que cualquiera de los acuerdos sobre la mesa situar\u00eda el valor de Alpine entre USD 2.000 y 2.500 millones, una cifra respaldada por el inter\u00e9s de actores como MSP Sports Capital. Adem\u00e1s, desde Alpine se aclar\u00f3 que las conversaciones y acercamientos involucran a los actuales accionistas, Otro Capital (poseedor del 24 %) y Renault Group (titular del 76 %), y no con el consejero ejecutivo Flavio Briatore ni directamente con el equipo.<\/p>\n<p>En las \u00faltimas semanas, Alpine confirm\u00f3 que Horner y su consorcio de inversores manifestaron su intenci\u00f3n de adquirir la participaci\u00f3n de Otro Capital (USD 600 millones, apr\u00f3ximadamente). La posibilidad de este movimiento toma forma en un contexto dif\u00edcil para el equipo, aunque con un futuro esperanzador: la estructura con sede en Enstone finaliz\u00f3 el Mundial de 2025 en el d\u00e9cimo y \u00faltimo puesto, con apenas 22 puntos (todos gracias a Pierre Gasly), sumados en 24 carreras, frente a los 833 puntos que logr\u00f3 McLaren, el campe\u00f3n de la temporada. A la espera del comienzo de la temporada, muchos posicionan a la escuder\u00eda de origen franc\u00e9s como una de las candidatas a luchas por estar a la cabeza del segundo pelot\u00f3n detr\u00e1s de Mercedes, Red Bull, Ferrari y McLaren.<\/p>\n<p>Desde el entorno inversor, la operaci\u00f3n se interpretar\u00eda como un paso inicial en el intento de reposicionar a Alpine en la \u00e9lite del automovilismo, dado su rezago en el \u00faltimo torneo. Una fuente consultada se\u00f1al\u00f3 la probabilidad de que Horner busque, en \u00faltima instancia, controlar el equipo en el que logre participar, aunque la postura de Renault respecto a ceder la mayor\u00eda accionaria no est\u00e1 clara.<\/p>\n<p>MSP Sports Capital es un actor protagonista en el escenario de los fondos de inversi\u00f3n deportivos y tiene experiencia previa en F\u00f3rmula 1. Durante el \u00faltimo oto\u00f1o, se desprendi\u00f3 de su participaci\u00f3n en McLaren Racing, como parte de un acuerdo que valor\u00f3 la escuder\u00eda brit\u00e1nica en aproximadamente USD 4.400 millones. Dicha operaci\u00f3n permiti\u00f3 a Mumtalakat, el fondo soberano de Bahr\u00e9in, y a CYVN Holdings de Abu Dabi, adquirir el 30 % restante de McLaren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-204575\" src=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU.avif\" alt=\"\" width=\"992\" height=\"680\" srcset=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU.avif 992w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU-150x103.jpg 150w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU-768x526.jpg 768w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU-613x420.jpg 613w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU-218x150.jpg 218w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU-696x477.jpg 696w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/QLJTFYCGWFAQFNL7CS4E7MN4GU-100x70.jpg 100w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/>En 2020, MSP Sports Capital lider\u00f3 la adquisici\u00f3n de un 15 % inicial en McLaren Racing, inversi\u00f3n que supuso una valoraci\u00f3n de unos USD 690 millones. Este flujo de capital result\u00f3 fundamental para apuntalar las finanzas del grupo McLaren durante la crisis sanitaria. M\u00e1s recientemente, la apreciaci\u00f3n del valor de la empresa refleja tanto el robustecimiento de su posici\u00f3n financiera como el destacado desempe\u00f1o deportivo.<\/p>\n<p>El atractivo que generan los activos vinculados a la F\u00f3rmula 1 no es exclusivo de Alpine ni de McLaren. Seg\u00fan financistas deportivos citados por Sky News, el inter\u00e9s inversor se mantiene s\u00f3lido, como evidencia el anuncio de Aston Martin de su intenci\u00f3n de vender su parte en el Grand Prix Team bajo una valoraci\u00f3n cercana a los 3.000 millones de d\u00f3lares, aunque ese acuerdo no se hizo p\u00fablico hasta la fecha.<\/p>\n<p>MSP Sports Capital y Christian Horner mantuvieron su reserva ante las solicitudes de comentarios planteadas por el sitio brit\u00e1nico. Horner, con dos d\u00e9cadas al frente de Red Bull Racing y un r\u00e9cord de seis t\u00edtulos de constructores y ocho de pilotos, con cuatro repartidos entre Sebastian Vettel y Max Verstappen, eval\u00faa distintas alternativas para regresar a la F1. La integraci\u00f3n de nuevos socios de capital, que incluir\u00eda tanto a inversionistas individuales como a oficinas familiares y fondos institucionales, acompa\u00f1a este proceso de exploraci\u00f3n estrat\u00e9gica.<\/p>\n<p>Por ahora, no se precis\u00f3 la identidad de otros posibles financiadores involucrados en las conversaciones, ni la probabilidad de que MSP Sports Capital concrete su participaci\u00f3n junto a Horner. Cabe recordar que el ex jefe acord\u00f3 con Red Bull una indemnizaci\u00f3n millonaria cercana a los 80.000.000 de libras esterlinas (m\u00e1s de 90 millones de euros). Se trat\u00f3 de una cifra que responde tanto a los a\u00f1os restantes de su contrato (que expiraba a finales de 2030) como a las cl\u00e1usulas de no competencia incluidas en el acuerdo. Ese tiempo ya se termin\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de volver a la M\u00e1xima El inter\u00e9s por una participaci\u00f3n en Alpine, el equipo que tiene como piloto titular al argentino Franco Colapinto atrajo a figuras destacadas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":204574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[28],"tags":[],"class_list":{"0":"post-204573","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1 - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1 - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T19:28:44+00:00\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1\",\"datePublished\":\"2026-02-10T19:28:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\"},\"wordCount\":890,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif\",\"articleSection\":[\"DEPORTES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\",\"name\":\"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1 - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif\",\"datePublished\":\"2026-02-10T19:28:44+00:00\",\"description\":\"La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de\",\"breadcrumb\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif\",\"width\":992,\"height\":558},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\/\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1 - Radio Infinita Goya","description":"La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/","og_locale":"es_ES","og_type":"article","og_title":"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1 - Radio Infinita Goya","og_description":"La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-02-10T19:28:44+00:00","author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1","datePublished":"2026-02-10T19:28:44+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/"},"wordCount":890,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif","articleSection":["DEPORTES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/","name":"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1 - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif","datePublished":"2026-02-10T19:28:44+00:00","description":"La inversi\u00f3n de USD 600 millones detr\u00e1s del acuerdo El ex director de Red Bull apunta a sumarse a la escuder\u00eda de Colapinto y Gasly en su apuesta de","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/6XTRTPFMQRFDFEPOUAZDCNCDJA.avif","width":992,"height":558},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/10\/el-plan-de-christian-horner-para-comprar-alpine-y-lograr-su-regreso-a-la-f1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"El plan de Christian Horner para comprar Alpine y lograr su regreso a la F1"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/204573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=204573"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/204573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/204574"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=204573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=204573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=204573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}