{"id":204604,"date":"2026-02-11T15:53:20","date_gmt":"2026-02-11T18:53:20","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=204604"},"modified":"2026-02-11T15:53:20","modified_gmt":"2026-02-11T18:53:20","slug":"ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/","title":{"rendered":"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa"},"content":{"rendered":"<p>La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de prensa este martes frente al edificio municipal para abordar la cr\u00edtica situaci\u00f3n generada por el cierre de la textil Alal. La conferencia se centr\u00f3 en las acciones coordinadas entre la provincia y la municipalidad para asistir a los trabajadores afectados.<\/p>\n<p>Mariel Gabur detall\u00f3 las gestiones realizadas ante el gobierno nacional para buscar soluciones, as\u00ed como la asistencia municipal que se proporcionar\u00e1 desde esta tarde, a trav\u00e9s de m\u00f3dulos de alimentos. Adem\u00e1s, anunci\u00f3 que se empadronar\u00e1 a los trabajadores para exenciones en el pago de servicios b\u00e1sicos. La ministra record\u00f3 el apoyo crediticio previo del gobierno provincial a la empresa, enfatizando que la sostenibilidad del empleo era una condici\u00f3n clave. &#8220;Lo ocurrido con la textil nos sorprendi\u00f3&#8221;, admiti\u00f3 Gabur.<\/p>\n<p>En un intercambio de preguntas y respuestas, la Ministra Gabur declar\u00f3: \u201cEstamos preocupados por la situaci\u00f3n. Trabajamos en distintas gestiones. El gobernador Juan Pablo Vald\u00e9s sigue minuto a minuto este tema. Le informamos c\u00f3mo se dan las distintas gestiones que hacemos. Ayer estuvimos con el gobierno nacional exponiendo la situaci\u00f3n de Corrientes. Hablamos con los empresarios para que busquen y encuentren las herramientas para darle soluci\u00f3n a los trabajadores, que son los m\u00e1s vulnerables. Estuve reunida con el secretario de Producci\u00f3n, Pablo Levigne. Planteamos esta situaci\u00f3n. Ellos tienen una mirada en la que podr\u00edan acompa\u00f1ar, pero son decisiones que se dan a largo plazo y nosotros ya no tenemos plazo. Eso hemos planteado. Lo que queremos es: qu\u00e9 herramientas podemos tener en lo inmediato para asistir a estas familias que est\u00e1n en esta situaci\u00f3n, sin trabajo\u201d.<\/p>\n<p>SERVICIOS B\u00c1SICOS<\/p>\n<p>Ante la pregunta de un periodista sobre las medidas anunciadas, como la suspensi\u00f3n de cortes de energ\u00eda y la entrega de bolsones alimentarios, la ministra respondi\u00f3: \u201cTodas a nivel provincial, vamos a seguir gestionando para ver si podemos lograr alguna asignaci\u00f3n que venga del gobierno nacional. Todo ser\u00e1 importante y el gobernador Juan Pablo Vald\u00e9s, con el intendente Mariano Hormaechea, y dependiendo de la reuni\u00f3n con la audiencia que tiene la empresa y los trabajadores para ma\u00f1ana, vamos a ir tomando las decisiones que puedan acompa\u00f1ar la situaci\u00f3n de vulnerabilidad de los trabajadores\u201d.<\/p>\n<p>En cuanto a la organizaci\u00f3n de los empleados, Gabur se\u00f1al\u00f3: \u201cLos trabajadores tienen su sindicato. Ellos son los que van a la audiencia y los que llevan la voz de los trabajadores. Son un grupo laboral que tiene sus delegados y ellos van a ir tomando las medidas, decisiones que consideren y siempre estando dentro de la legalidad. El gobierno, a trav\u00e9s de la Secretar\u00eda de Trabajo y mi \u00e1rea, ministerio, los vamos a estar acompa\u00f1ando\u201d.<\/p>\n<p>SITUACI\u00d3N TRABADA<\/p>\n<p>El director de Prensa Alejandro Medina, presente en la rueda de prensa, indic\u00f3: \u201cAOT y SETIA nuclean a los empleados. Los representantes tuvieron las audiencias en Buenos Aires y la Subsecretar\u00eda de Trabajo. Queda esta reuni\u00f3n de ma\u00f1ana mi\u00e9rcoles, a ver si se puede llegar a avanzar en algo, porque est\u00e1 trabada la situaci\u00f3n\u201d.<\/p>\n<p>La ministra respondi\u00f3 a Medina: \u201cLas audiencias se van dando paulatinamente. Gestionamos y hablamos con los representantes de la empresa para que busquen remedios inmediatos para asegurar la vida de los trabajadores que hoy no perciben nada y necesitan seguir alimentando sus familias, sus hogares, y eso es lo inmediato. Igualmente, el gobierno provincial tom\u00f3 las medidas, y otras que el gobernador seguramente ir\u00e1 acompa\u00f1ando de acuerdo a c\u00f3mo se lleve la situaci\u00f3n\u201d.<\/p>\n<p>Ante la consulta sobre la respuesta de las empresas, Gabur respondi\u00f3: \u201cEstoy en comunicaci\u00f3n con ellos. Ellos dicen que no tienen fondos para asumir las indemnizaciones y que lo est\u00e1n gestionando. Esa es la respuesta\u201d.<\/p>\n<p>INTENDENTE HORMAECHEA<\/p>\n<p>Tambi\u00e9n el periodista Alejandro Medina destac\u00f3 la inmediatez de la ayuda provincial y municipal, mencionando el m\u00f3dulo alimentario y el empadronamiento de los trabajadores. El intendente Hormaechea respondi\u00f3: \u201cAs\u00ed es, es uno de los planteos que se hizo en reuniones previas. Estuvimos en contacto con la ministra trabajando con la situaci\u00f3n. Hoy se ha tomado la decisi\u00f3n de acompa\u00f1ar con ese pedido de asistencia, que se har\u00e1 a la tarde desde las 16 en la Asistencia Municipal, en un trabajo conjunto con el Ministerio de Desarrollo Social de la provincia. A trav\u00e9s de ah\u00ed se gestion\u00f3 esto; y aprovecharemos para que cada trabajador denuncie su domicilio y se hagan las gestiones formales a trav\u00e9s de la DPEC\u201d.<\/p>\n<p>M\u00d3DULOS ALIMENTARIOS<\/p>\n<p>Ante la pregunta sobre la periodicidad del m\u00f3dulo alimentario, Hormaechea respondi\u00f3: \u201cLo vamos a ir llevando de acuerdo a lo que vaya sucediendo. Ma\u00f1ana tenemos la audiencia, pero vimos necesario hacer esa primera asistencia. Veremos lo que pasa en la audiencia, esperemos tener una respuesta positiva, en base a lo que piden los trabajadores que se les pague y ah\u00ed evaluaremos la futura asistencia\u201d.<\/p>\n<p>Sobre el rol de la provincia y el municipio en esta situaci\u00f3n de los trabajadores de Alal, Hormaechea explic\u00f3: \u201cBueno, lo estamos haciendo de esa manera, escuchando a los trabajadores, recibi\u00e9ndolos, haciendo las gestiones ante el gobierno provincial, y este ante el gobierno nacional, tratando de asistir de esta manera. Fue una petici\u00f3n de los mismos trabajadores el tema del m\u00f3dulo alimentario, la cuesti\u00f3n de la energ\u00eda y el agua, y por supuesto, el equipo del gobierno de la provincia que participa desde los organismos en las mediaciones que se est\u00e1n haciendo con los trabajadores, y una de esas es ma\u00f1ana\u201d.<\/p>\n<p>CR\u00c9DITO OTORGADO ANTES<\/p>\n<p>En relaci\u00f3n al cr\u00e9dito otorgado a la empresa textil con anterioridad, la ministra aclar\u00f3: \u201cYo aclaro que el cr\u00e9dito fue otorgado con anterioridad, en el mes de junio o julio, no es a tasa cero sino con tasa subsidiada. Las tasas bancarias estaban en un 70 u 75 por ciento, se subsidi\u00f3 un 50 por ciento de la tasa, casi, no era tasa cero, y con toda la raz\u00f3n, una de las intenciones m\u00e1s importantes del apoyo que hace el gobierno provincial es mantener las fuentes laborales. Por eso nos tom\u00f3 por sorpresa, siendo que en esta cuesti\u00f3n yo sigo siendo la misma ministra de la gesti\u00f3n anterior, y que acompa\u00f1o ahora al gobernador Pablo Vald\u00e9s. Nos tom\u00f3 por sorpresa\u201d, insisti\u00f3. \u201cTrabajamos con todas las empresas, sabemos que pasan un momento dif\u00edcil, por eso anunci\u00e9 en diciembre que las textiles pasaban momentos dif\u00edciles. Venimos gestionando acciones ante el gobierno nacional y viendo cu\u00e1l es el camino que tiene trazado el gobierno nacional para que las industrias que han adquirido tecnolog\u00eda queden dentro del sistema, que es lo que nos plantearon: que si las industrias no adquir\u00edan tecnolog\u00eda y no bajaban los costos y no eran eficientes, podr\u00edan llegar a desaparecer. Justamente, el gobierno trat\u00f3 de apalancar la industria que necesita inversiones en tecnolog\u00eda para poder sortear esta situaci\u00f3n que hoy lamentablemente Alal, nos encontramos que no ha logrado. Sabemos que han comprado las m\u00e1quinas, entiendo el dolor de los trabajadores, la desesperaci\u00f3n, entiendo las expresiones que han tenido, por eso es muy dif\u00edcil hablar delante de tantos trabajadores, cada uno tiene su situaci\u00f3n personal, est\u00e1n golpeados an\u00edmicamente. Los he escuchado, es dif\u00edcil responderles, pero hemos controlado que las inversiones se hayan hecho dentro de lo que se ha planificado: maquinarias para pasar al siguiente eslab\u00f3n que es la tejedur\u00eda\u201d.<\/p>\n<p>Consultada sobre la situaci\u00f3n de otras industrias textiles, la ministra respondi\u00f3: \u201cLa verdad es que est\u00e1n pasando por un momento muy dif\u00edcil, est\u00e1n en situaciones con m\u00e1rgenes peque\u00f1os, trabajan a p\u00e9rdida. Muchas industrias trabajan a p\u00e9rdida hasta que logran encauzar y recuperar esas p\u00e9rdidas, que van surgiendo cuando hay proyectos a futuro que indican que se podr\u00edan recuperar\u201d.<\/p>\n<p>CONTROL DE IRREGULARIDADES<\/p>\n<p>Ante la denuncia de trabajadores sobre actividad nocturna en la empresa y posible vaciamiento, Gabur afirm\u00f3: \u201cLa empresa todav\u00eda est\u00e1 en manos de los empresarios, es una empresa privada, podr\u00edan sacar lo que est\u00e1 ah\u00ed adentro, lo que s\u00ed, si hay trabajadores que est\u00e1n trabajando irregularmente, vamos a mandar una inspecci\u00f3n porque eso no podr\u00eda estar ocurriendo\u201d.<\/p>\n<p>La ministra confirm\u00f3 que las p\u00e9rdidas mensuales de la empresa rondan los 900 millones de pesos, sumando las p\u00e9rdidas de diciembre y enero.<\/p>\n<p>POSTURA DEL GOBIERNO NACIONAL<\/p>\n<p>En cuanto a la reuni\u00f3n con el ministro Caputo, Gabur explic\u00f3: \u201cEn esa reuni\u00f3n hablamos de todo el proceso que tiene establecido el gobierno nacional para que las industrias que han invertido en tecnolog\u00eda, en el caso de todas las correntinas, est\u00e9n en condiciones de exportar y no solamente hilander\u00eda sino tambi\u00e9n algo de tejedur\u00eda, es decir la tela. Lo que sale caro en la Argentina es la mano de obra para la confecci\u00f3n, por lo tanto, podr\u00eda ser un camino la venta tanto de hilander\u00eda como la tela; hay empresas nuestras que est\u00e1n exportando. El caso de Alal: comenzaron a exportar, tuvieron problemas en la calidad de la producci\u00f3n que mandaron, eso signific\u00f3 un corte en la mercader\u00eda y lo que recae inmediatamente en un rev\u00e9s econ\u00f3mico que aparentemente los pone en esta situaci\u00f3n\u201d.<\/p>\n<p>Gabur detall\u00f3: \u201cLas exportaciones fueron a Per\u00fa, Colombia, Paraguay. Colombia ha rechazado el producto por no mantener las mismas calidades que tiene el hilado de India. Tenemos una cuesti\u00f3n de calidad de algod\u00f3n, sobre todo en la cosecha. Tenemos la cosecha a m\u00e1quina, donde entran elementos naturales, que no son puramente algod\u00f3n; sin embargo, pa\u00edses como India tienen cosecha manual a trav\u00e9s de las mujeres, lo que en la Argentina no estar\u00eda dentro de los est\u00e1ndares que manejamos, son cosecha en temporada, con horas extendidas\u201d. Confirm\u00f3 que la segunda tanda de contenedores enviados fue rechazada.<\/p>\n<p>EN CONDICIONES DE COMPETIR<\/p>\n<p>Consultada sobre la viabilidad de la industria textil en el contexto nacional, la ministra expres\u00f3: \u201cCreemos que nuestras industrias est\u00e1n en condiciones de competir, han adquirido tecnolog\u00eda, se han tecnificado por lo menos las que est\u00e1n en Corrientes. Ayer, en la reuni\u00f3n surgieron distintas cuestiones, estamos en condiciones, las industrias de Corrientes han adquirido tecnolog\u00eda, muchas de ellas con el apoyo del gobierno provincial. Son distintas herramientas y modelos que hemos brindado. Est\u00e1n tecnificadas, est\u00e1n exportando, necesitamos, y por eso trabajamos con el gobierno nacional para quitar cualquier tipo de medidas como aranceles que le dan un costo extra. Si se trabaja en la quita de aranceles, estamos en condiciones de competir con un hilado de buena calidad, y que podr\u00eda incluso mejorar si se tecnifica con el ingreso de semillas de algod\u00f3n de mejor calidad\u201d.<\/p>\n<p>Finalmente, mencion\u00f3 a Tipoity, Alpargatas, la planta de Monte Caseros y Textil Ibera como ejemplos de empresas correntinas con buena calidad en su producci\u00f3n de algod\u00f3n.<\/p>\n<p>La situaci\u00f3n en torno a la textil Alal sigue siendo incierta, y la reuni\u00f3n del mi\u00e9rcoles entre la empresa, los trabajadores y las autoridades ser\u00e1 crucial para definir los pr\u00f3ximos pasos a seguir.<\/p>\n<p>Direcci\u00f3n de Prensa \u2013 Municipalidad de Goya<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de prensa este martes frente al edificio municipal para abordar la cr\u00edtica situaci\u00f3n generada por el cierre de la textil Alal. La conferencia se centr\u00f3 en las acciones coordinadas entre la provincia y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":204605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[27],"tags":[],"class_list":{"0":"post-204604","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T18:53:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa\",\"datePublished\":\"2026-02-11T18:53:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\"},\"wordCount\":1935,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg\",\"articleSection\":[\"LOCALES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\",\"name\":\"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg\",\"datePublished\":\"2026-02-11T18:53:20+00:00\",\"description\":\"La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de\",\"breadcrumb\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg\",\"width\":848,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\/\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa - Radio Infinita Goya","description":"La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/","og_locale":"es_ES","og_type":"article","og_title":"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa - Radio Infinita Goya","og_description":"La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-02-11T18:53:20+00:00","og_image":[{"width":848,"height":477,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg","type":"image\/jpeg"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa","datePublished":"2026-02-11T18:53:20+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/"},"wordCount":1935,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg","articleSection":["LOCALES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/","name":"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg","datePublished":"2026-02-11T18:53:20+00:00","description":"La ministra de Industria, Trabajo y Comercio de la provincia de Corrientes, Mariel Gabur, junto al intendente Mariano Hormaechea, ofrecieron una rueda de","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/empadronamiento_trabajadores_alal.jpg","width":848,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/ministra-gabur-y-el-intendente-abordan-crisis-textil-alal-en-rueda-de-prensa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"Ministra Gabur y el Intendente abordan crisis Textil Alal en rueda de prensa"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/204604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=204604"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/204604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/204605"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=204604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=204604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=204604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}