{"id":204622,"date":"2026-02-11T16:20:25","date_gmt":"2026-02-11T19:20:25","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=204622"},"modified":"2026-02-11T16:20:25","modified_gmt":"2026-02-11T19:20:25","slug":"el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/","title":{"rendered":"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida"},"content":{"rendered":"<p>En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para frenar la influencia de China.<\/p>\n<p>Argentina participa este mi\u00e9rcoles en Washington en una reuni\u00f3n convocada por el Pent\u00e1gono para altos mandos militares de 34 pa\u00edses del hemisferio occidental, que estar\u00e1 focalizada en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para frenar la influencia de China.<\/p>\n<p>El encuentro, que fue calificado como \u201cinusual\u201d por The New York Times e \u201cimportante y notable\u201d por expertos consultados por Clar\u00edn, fue convocado semanas atr\u00e1s por el jefe del Estado Mayor Conjunto de Estados Unidos, Dan Caine.<\/p>\n<p>Argentina est\u00e1 representada por su contraparte, Marcelo Dalle Nogare, que viaj\u00f3 especialmente para esta reuni\u00f3n clave que comenzar\u00e1 con un desayuno temprano en la ma\u00f1ana y se extender\u00e1 hasta la tarde en un hotel del centro de la capital estadounidense.<\/p>\n<p>La cita fue convocada para &#8220;las naciones de todo el hemisferio occidental que comparten profundos lazos hist\u00f3ricos, valores comunes e inter\u00e9s en la estabilidad regional que apoya la seguridad y prosperidad a largo plazo para Estados Unidos y nuestro vecindario compartido&#8221;, seg\u00fan dijo el ej\u00e9rcito estadounidense en el anuncio.<\/p>\n<p>&#8220;Los l\u00edderes de defensa participantes explorar\u00e1n la importancia de asociaciones s\u00f3lidas, cooperaci\u00f3n continua y esfuerzos unidos para contrarrestar organizaciones criminales y terroristas, as\u00ed como actores externos que socavan la seguridad y estabilidad regional&#8221;, afirmaron.<\/p>\n<p>La reuni\u00f3n incluye a pa\u00edses de la regi\u00f3n \u2013con la probable excepci\u00f3n de Cuba y Nicaragua\u2014 y tambi\u00e9n altos mandos militares de Dinamarca, Francia y Gran Breta\u00f1a, que tienen territorios en la regi\u00f3n. El gobierno dan\u00e9s, por ejemplo, controla Groenlandia, una isla del \u00c1rtico considerada estrat\u00e9gica para la defensa de Estados Unidos.<\/p>\n<p>El encuentro se enmarca en el reciente lanzamiento de la llamada \u201cDoctrina Donroe\u201d, una especie de \u201cDoctrina Monroe versi\u00f3n Trump\u201d, donde Estados Unidos muestra su nueva estrategia de Defensa, que pone el foco en el hemisferio occidental.<\/p>\n<p>En ese documento de cerca de 30 p\u00e1ginas, el Pent\u00e1gono se\u00f1al\u00f3 que \u201ctras a\u00f1os de abandono, el departamento de Guerra restaurar\u00e1 el dominio militar estadounidense en el hemisferio occidental. Lo utilizaremos para proteger nuestra patria y nuestro acceso a territorios estrat\u00e9gicos en toda la regi\u00f3n\u201d, se\u00f1al\u00f3 el documento.<\/p>\n<p>\u201cImpediremos que nuestros adversarios desplieguen fuerzas u otras capacidades que representen una amenaza a nuestro hemisferio\u201d, dijo en referencia a China. \u201cLo m\u00e1s importante es la defensa del territorio nacional y la disuasi\u00f3n de China\u201d, a\u00f1adi\u00f3 el documento.<\/p>\n<p>La reuni\u00f3n de altos mandos se produce tras la controvertida captura de Nicol\u00e1s Maduro en Venezuela y los sucesivos ataques a lanchas que supuestamente traficaban drogas en el Caribe y el Atl\u00e1ntico, con decenas de muertos. En el hemisferio tambi\u00e9n hay tensiones con Canad\u00e1 y M\u00e9xico por aranceles y con Europa por la ambici\u00f3n de Trump sobre Groenlandia.<\/p>\n<p>La reuni\u00f3n es &#8220;importante y notable&#8221;, dijo a Clar\u00edn Evan Ellis, profesor de estudios latinoamericanos en el Instituto de Estudios Estrat\u00e9gicos de la Escuela de Guerra del Ej\u00e9rcito de EE.UU. \u201cEs inusual que EE. UU. convoque tal reuni\u00f3n, centrada en un punto del orden del d\u00eda especificado por ellos\u201d, expres\u00f3.<\/p>\n<p>Seg\u00fan el experto, el foco de la reuni\u00f3n girar\u00e1 sobre la lucha contra el crimen organizado transnacional y el narcotr\u00e1fico en la regi\u00f3n, as\u00ed como tambi\u00e9n la miner\u00eda ilegal, la extorsi\u00f3n, la trata de personas, el blanqueo de capitales y otros delitos. &#8220;Por supuesto, tambi\u00e9n estar\u00e1 la influencia de China y hay que recordar que China ha convocado, durante varios a\u00f1os, a un subconjunto de altos l\u00edderes de defensa latinoamericanos a trav\u00e9s del Foro de Defensa China-Celac\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Justamente el d\u00eda anterior a la reuni\u00f3n militar, congresistas hispanos presentaron la iniciativa del &#8216;Buen vecino&#8217;, que busca anular la Doctrina Monroe revivida por el presidente Trump, mientras condenaron la intervenci\u00f3n en Venezuela, las amenazas de bombardear M\u00e9xico y el nuevo bloqueo de petr\u00f3leo a Cuba.<\/p>\n<p>Casi 20 legisladores dem\u00f3cratas, liderados por la representante Nydia Vel\u00e1zquez de Nueva York, dieron curso a la propuesta. &#8220;El Departamento de Estado debe confirmar formalmente que la Doctrina Monroe ya no es pol\u00edtica estadounidense. Durante 200 a\u00f1os ha justificado intervenciones, golpe de Estado y apoyo a dictaduras desde Chile hasta Guatemala y Brasil, y la Rep\u00fablica Dominicana tambi\u00e9n&#8221;, expres\u00f3 Vel\u00e1zquez al anunciar el planteamiento.<\/p>\n<p>La nueva Estrategia de Seguridad Nacional de Trump publicada en diciembre afirma que &#8220;tras a\u00f1os de abandono, Estados Unidos reafirmar\u00e1 y aplicar\u00e1 la Doctrina Monroe para restaurar la preeminencia estadounidense en el hemisferio occidental&#8221;.<\/p>\n<p>La congresista Vel\u00e1zquez justific\u00f3 la resoluci\u00f3n &#8220;porque la doctrina Trump, &#8216;Donroe&#8217; Trump, es un regreso peligroso al intervencionismo fallido&#8221;.<\/p>\n<p>La estrategia de EE.UU. se complementa con el lanzamiento la semana pasada de un acuerdo marco sobre minerales cr\u00edticos, considerados clave para la defensa y seguridad nacional por el gobierno de Trump, que apunta a asegurar el acceso a esas riquezas en el continente americano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para frenar la influencia de China. Argentina participa este mi\u00e9rcoles en Washington en una reuni\u00f3n convocada por el Pent\u00e1gono para altos mandos militares de 34 pa\u00edses del hemisferio occidental, que estar\u00e1 focalizada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":204623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[29],"tags":[],"class_list":{"0":"post-204622","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T19:20:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida\",\"datePublished\":\"2026-02-11T19:20:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\"},\"wordCount\":898,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\",\"name\":\"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg\",\"datePublished\":\"2026-02-11T19:20:25+00:00\",\"description\":\"En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para\",\"breadcrumb\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg\",\"width\":680,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\/\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida - Radio Infinita Goya","description":"En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/","og_locale":"es_ES","og_type":"article","og_title":"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida - Radio Infinita Goya","og_description":"En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-02-11T19:20:25+00:00","og_image":[{"width":680,"height":340,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg","type":"image\/jpeg"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida","datePublished":"2026-02-11T19:20:25+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/"},"wordCount":898,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg","articleSection":["NACIONALES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/","name":"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg","datePublished":"2026-02-11T19:20:25+00:00","description":"En encuentro est\u00e1 focalizado en la nueva estrategia del gobierno de Donald Trump para la regi\u00f3n, donde el republicano busca tener mayor protagonismo para","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/02\/4UCyZz_5.jpg","width":680,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/02\/11\/el-pentagono-organizo-una-cumbre-de-altos-mandos-militares-argentina-esta-incluida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"El Pent\u00e1gono organiz\u00f3 una cumbre de altos mandos militares, Argentina est\u00e1 incluida"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/204622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=204622"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/204622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/204623"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=204622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=204622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=204622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}