{"id":210986,"date":"2026-03-27T16:20:12","date_gmt":"2026-03-27T19:20:12","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=210986"},"modified":"2026-03-27T16:20:12","modified_gmt":"2026-03-27T19:20:12","slug":"detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/","title":{"rendered":"Detectan una tonelada de pescado camuflado entre cajones de verdura"},"content":{"rendered":"<p>El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos.<\/p>\n<p>A d\u00edas del Viernes Santo, un control de rutina en una ruta de C\u00f3rdoba revel\u00f3 el hallazgo de una importante carga de pescado que era trasladada desde Santa Fe sin cumplir las normas sanitarias vigentes y sin respetar la cadena de fr\u00edo: estaban escondidos entre cajones de verduras.<\/p>\n<p>El procedimiento se llev\u00f3 a cabo en la madrugada del jueves, cuando personal de Gendarmer\u00eda Nacional detect\u00f3 un cami\u00f3n que transportaba cerca de una tonelada de s\u00e1balo en condiciones insalubres.<\/p>\n<p>Informate m\u00e1sAlerta por lluvias en Buenos Aires: 5 de los pr\u00f3ximos 7 d\u00edas estar\u00e1n pasados por agua<\/p>\n<p>El operativo tuvo lugar pasadas las 5 de la ma\u00f1ana, a la altura del Peaje Devoto, sobre la Ruta Nacional N\u00b0 19, en el kil\u00f3metro 142. All\u00ed, efectivos de la Secci\u00f3n Seguridad Vial &#8220;San Francisco&#8221;, dependientes del Escuadr\u00f3n de Seguridad Vial &#8220;Villa Mar\u00eda&#8221;, detuvieron al veh\u00edculo para una inspecci\u00f3n de rutina.<\/p>\n<p>Seg\u00fan informaron desde Gendarmer\u00eda, el cami\u00f3n proven\u00eda de la localidad de Santa Rosa, en la provincia de Santa Fe, y se dirig\u00eda hacia la ciudad de C\u00f3rdoba. A simple vista, dentro del acoplado llevaba una importante carga de verduras.<\/p>\n<p>Sin embargo, durante una revisi\u00f3n m\u00e1s exhaustiva, los gendarmes descubrieron que entre los productos hab\u00eda 41 cajas con ejemplares de s\u00e1balo que eran transportados sin las condiciones adecuadas de refrigeraci\u00f3n.<\/p>\n<p>La mercader\u00eda se encontraba en infracci\u00f3n a la Ley 22.375, que regula aspectos vinculados a la sanidad animal y las condiciones de transporte de alimentos. De acuerdo con la documentaci\u00f3n presentada, el valor de la carga ascend\u00eda a unos 3.800.000 pesos.<\/p>\n<p>Tras el hallazgo, se dio intervenci\u00f3n a personal del Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA), delegaci\u00f3n San Francisco. Se realizaron las actuaciones correspondientes y se dispuso el secuestro de la mercader\u00eda. Posteriormente, personal de Bromatolog\u00eda llev\u00f3 adelante el decomiso y traslad\u00f3 los pescados, previamente embolsados, a una c\u00e1mara frigor\u00edfica para su resguardo.<\/p>\n<p>Finalmente, se inform\u00f3 que la carga qued\u00f3 a disposici\u00f3n del Juzgado de Faltas de San Francisco, que determinar\u00e1 los pasos a seguir en el caso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas del Viernes Santo, un control de rutina en una ruta de C\u00f3rdoba revel\u00f3 el hallazgo de una importante carga de pescado que era trasladada desde Santa Fe sin [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":210987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[29],"tags":[],"class_list":{"0":"post-210986","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detectan una tonelada de pescado camuflado entre cajones de verdura - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detectan una tonelada de pescado camuflado entre cajones de verdura - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T19:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"285\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"Detectan una tonelada de pescado camuflado entre cajones de verdura\",\"datePublished\":\"2026-03-27T19:20:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\",\"name\":\"Detectan una tonelada de pescado camuflado entre cajones de verdura - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp\",\"datePublished\":\"2026-03-27T19:20:12+00:00\",\"description\":\"El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas\",\"breadcrumb\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp\",\"width\":380,\"height\":285},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detectan una tonelada de pescado camuflado entre cajones de verdura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#website\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"contentUrl\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\/\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detectan una tonelada de pescado camuflado entre cajones de verdura - Radio Infinita Goya","description":"El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/","og_locale":"es_ES","og_type":"article","og_title":"Detectan una tonelada de pescado camuflado entre cajones de verdura - Radio Infinita Goya","og_description":"El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-03-27T19:20:12+00:00","og_image":[{"width":380,"height":285,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp","type":"image\/webp"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"Detectan una tonelada de pescado camuflado entre cajones de verdura","datePublished":"2026-03-27T19:20:12+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp","articleSection":["NACIONALES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/","name":"Detectan una tonelada de pescado camuflado entre cajones de verdura - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp","datePublished":"2026-03-27T19:20:12+00:00","description":"El peligroso cargamento era transportado en un cami\u00f3n y ten\u00eda como destino final la ciudad de C\u00f3rdoba. Estaba valuado en casi 4 millones de pesos. A d\u00edas","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/03\/282804w380h285c.jpg.webp","width":380,"height":285},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/03\/27\/detectan-una-tonelada-de-pescado-camuflado-entre-cajones-de-verdura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"Detectan una tonelada de pescado camuflado entre cajones de verdura"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/210986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=210986"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/210986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/210987"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=210986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=210986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=210986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}