{"id":223200,"date":"2026-07-18T16:48:32","date_gmt":"2026-07-18T19:48:32","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=223200"},"modified":"2026-07-18T16:48:32","modified_gmt":"2026-07-18T19:48:32","slug":"cuatreros-en-corrientes-los-detuvieron-hace-dos-dias","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/","title":{"rendered":"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas"},"content":{"rendered":"<p>Y ayer volvieron a caer con carne clandestina<\/p>\n<p>La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener su correlato en los estamentos judiciales. El mi\u00e9rcoles pasado efectivos del PRIAR de Saladas detuvieron un auto por RP13 llevando una vaca faenada. Dertuvieron a dos. Ayer, en otro procedimiento, los mismos sujetos fueron descubiertos cuando arreaban ganado ajeno<\/p>\n<p>Una investigaci\u00f3n de la Polic\u00eda Rural y Ecol\u00f3gica de Saladas, que se inici\u00f3 tras el secuestro de un veh\u00edculo con m\u00e1s de 400 kilos de carne presuntamente de origen ilegal, culmin\u00f3 con un importante allanamiento en un establecimiento rural donde fueron detenidas tres personas y secuestrados 12 bovinos con aparentes marcas adulteradas, adem\u00e1s de herramientas de faena, hierros para marcar hacienda, tel\u00e9fonos celulares y una camioneta.<br \/>\nDurante el procedimiento, los efectivos hallaron cuchillos, serruchos, ganchos para oreo, restos de faena clandestina, v\u00edsceras ocultas en un estero y cueros vacunos, evidencias que reforzaron la investigaci\u00f3n. En plena diligencia sorprendieron a tres hombres arreando 38 animales sin autorizaci\u00f3n. Tras la inspecci\u00f3n, se detectaron irregularidades en las marcas de doce bovinos, que fueron secuestrados para las pericias correspondientes.<\/p>\n<p>Por disposici\u00f3n de la fiscal subrogante de la U.F.R.A.C. de Saladas, Dra. Nancy Ver\u00f3nica Corbal\u00e1n Maldonado, fueron aprehendidos Fernando Sebasti\u00e1n Niz, Roberto Vallejos y Zacar\u00edas Almir\u00f3n. La causa fue recaratulada como &#8220;Supuesto Abigeato Agravado en Flagrancia&#8221;, mientras la Polic\u00eda Rural contin\u00faa con la investigaci\u00f3n para determinar el alcance de la maniobra y la posible participaci\u00f3n de m\u00e1s involucrados<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-223202\" src=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg-600x600.webp\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg-600x600.webp 600w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg-150x150.webp 150w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg-768x768.webp 768w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg-420x420.webp 420w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg-696x696.webp 696w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289532w790h790c.jpg.webp 790w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Los mismos<br \/>\nEl mi\u00e9rcoles, en un operativo de la Polic\u00eda Rural y Ecol\u00f3gica de Saladas, se intercept\u00f3 un autom\u00f3vil que transportaba 478,2 kilos de carne vacuna, equivalentes pr\u00e1cticamente a una vaca entera faenada, presuntamente de origen ilegal.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-223203\" src=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg-600x600.webp\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg-600x600.webp 600w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg-150x150.webp 150w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg-768x768.webp 768w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg-420x420.webp 420w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg-696x696.webp 696w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289533w790h790c.jpg.webp 790w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Ayer, los volvieron a descubrir llevando animales a un campo al cu\u00e1l ingresaron.<br \/>\nTras otro allanamiento, descubrieron cueros, garrones y las marcas planchadas, enterradas y escondidas en lagunas<\/p>\n<p>La Polic\u00eda sostiene que son los mismos integrantes de la banda que viene robando ganado en campos de la zona. Seg\u00fan la fuente, uno de los sujetos detenidos tiene un local en Saladas donde comercializa la carne robada<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-223204\" src=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg-600x600.webp\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg-600x600.webp 600w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg-150x150.webp 150w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg-768x768.webp 768w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg-420x420.webp 420w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg-696x696.webp 696w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289534w790h790c.jpg.webp 790w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener su correlato en los estamentos judiciales. El mi\u00e9rcoles pasado efectivos del PRIAR de Saladas detuvieron un auto por RP13 llevando una vaca faenada. Dertuvieron a dos. Ayer, en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":223201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[26],"tags":[],"class_list":["post-223200","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuatreros en Corrientes: los detuvieron hace dos d\u00edas - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-18T19:48:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289535w850h451c.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas\",\"datePublished\":\"2026-07-18T19:48:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/289535w850h451c.jpg.webp\",\"articleSection\":[\"PROVINCIALES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/\",\"name\":\"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/289535w850h451c.jpg.webp\",\"datePublished\":\"2026-07-18T19:48:32+00:00\",\"description\":\"Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/289535w850h451c.jpg.webp\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/289535w850h451c.jpg.webp\",\"width\":850,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Infinita-Goya-100063870918311\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas - Radio Infinita Goya","description":"Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas - Radio Infinita Goya","og_description":"Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-07-18T19:48:32+00:00","og_image":[{"width":850,"height":451,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289535w850h451c.jpg.webp","type":"image\/webp"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas","datePublished":"2026-07-18T19:48:32+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289535w850h451c.jpg.webp","articleSection":["PROVINCIALES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/","name":"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289535w850h451c.jpg.webp","datePublished":"2026-07-18T19:48:32+00:00","description":"Y ayer volvieron a caer con carne clandestina La lucha que lleva adelante la Polic\u00eda de Corrientes contra el abigeato no da tregua, pero no parece tener","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289535w850h451c.jpg.webp","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/289535w850h451c.jpg.webp","width":850,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/cuatreros-en-corrientes-los-detuvieron-hace-dos-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"Cuatreros en Corrientes: los detuvieron hace dos d\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/223200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=223200"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/223200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/223201"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=223200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=223200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=223200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}