{"id":223219,"date":"2026-07-18T17:09:38","date_gmt":"2026-07-18T20:09:38","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=223219"},"modified":"2026-07-18T17:09:38","modified_gmt":"2026-07-18T20:09:38","slug":"franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/","title":{"rendered":"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1"},"content":{"rendered":"<p>El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar.<\/p>\n<p>Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1, tras haber sido eliminado en la Q2. Despu\u00e9s de los entrenamientos del viernes, cierra el s\u00e1bado con con una actuaci\u00f3n algo irregular.<\/p>\n<p>El argentino hab\u00eda terminado 13\u00b0 y logr\u00f3 escalar posiciones respecto del viernes gracias a las sanciones a Lando Norris e Isaack Hadjar. Colapinto empez\u00f3 corriendo desde atr\u00e1s, pero logr\u00f3 remontar gracias a los neum\u00e1ticos blandos sobre los \u00faltimos minutos.<\/p>\n<p>Otro aspecto positivo es que logr\u00f3 quedar apenas por debajo de su compa\u00f1ero de escuder\u00eda, Pierre Gasly, quien termin\u00f3 10\u00b0. El tiempo del argentino 1:46.392, quedando 0.061 del registro del franc\u00e9s (1:46.331), siendo una tanda muy pareja para los Alpine.<\/p>\n<p>C\u00f3mo le fue a Franco Colapinto en la tercera y \u00faltima prueba libre<\/p>\n<p>El piloto de Alpine volvi\u00f3 a exhibir una s\u00f3lida adaptaci\u00f3n al desafiante trazado belga a bordo de su Alpine. Aunque su primer intento de vuelta r\u00e1pida fue invalidado por las autoridades de la carrera al exceder los l\u00edmites de la pista, el piloto argentino logr\u00f3 mantener la concentraci\u00f3n y, justo sobre la bandera a cuadros, consolid\u00f3 su registro definitivo con el caucho blando para ubicarse en la decimotercera posici\u00f3n del clasificador.<\/p>\n<p>La tercera sesi\u00f3n de entrenamientos libres del Gran Premio de B\u00e9lgica en Spa-Francorchamps tuvo como principal protagonista a Kimi Antonelli, quien logr\u00f3 imponerse en lo m\u00e1s alto de la tabla de tiempos. Detr\u00e1s del piloto italiano se ubicaron Lando Norris y Max Verstappen como sus perseguidores m\u00e1s inmediatos, en una sesi\u00f3n que no estuvo exenta de drama debido a varios incidentes mec\u00e1nicos y accidentes que interrumpieron el rodaje en la pista.<\/p>\n<p>C\u00f3mo le fue a Franco Colapinto en las pruebas libres del viernes<br \/>\nTras un arranque prometedor en la primera sesi\u00f3n de entrenamientos del vierne, donde Franco Colapinto fue 15\u00b0 y registr\u00f3 un tiempo de 1:49.403 superando a su compa\u00f1ero Pierre Gasly por 309 mil\u00e9simas, el piloto argentino mejor\u00f3 en la segunda pr\u00e1ctica libre. En esta FP2, Colapinto detuvo el cron\u00f3metro en un destacado 1:47.147 que lo catapult\u00f3 a la 7\u00b0 posici\u00f3n.<\/p>\n<p>Pierre Gasly, por su parte, quien sufri\u00f3 m\u00faltiples contratiempos: vio c\u00f3mo le quitaban sus registros por exceder los l\u00edmites de la pista y qued\u00f3 relegado al 18\u00b0 lugar con una marca de 1:48.955. Por \u00faltimo, termin\u00f3 la jornada protagonizando un fuerte accidente sobre el cierre que oblig\u00f3 a desplegar la bandera roja.<\/p>\n<p>El trazado del m\u00edtico Spa-Francorchamps, ubicado en la regi\u00f3n de las Ardenas, combina tanto rectas largas, cambios de elevaci\u00f3n y, posiblemente, las curvas m\u00e1s importantes del automovilismo. La extensi\u00f3n total es de 7,004 kil\u00f3metros, cuenta con 19 curvas y donde habr\u00e1 un total de 44 vueltas.<\/p>\n<p>El argentino buscar\u00e1 mantener su buena performance en la m\u00e1xima categor\u00eda del automovilismo. En el mismo circuito, en el a\u00f1o 2025, termin\u00f3 en la 19\u00b0 posici\u00f3n.<\/p>\n<p>A qu\u00e9 hora corre Franco Colapinto en el GP de B\u00e9lgica de la F\u00f3rmula 1<br \/>\nS\u00e1bado 18 de julio<\/p>\n<p>Clasificaci\u00f3n: 11.00 (Argentina) \/ 16.00 (B\u00e9lgica)<\/p>\n<p>Domingo 19 de julio<\/p>\n<p>Carrera a 44 vueltas: 10.00 (Argentina) \/ 15.00 (B\u00e9lgica)<\/p>\n<p>TV: Fox Sports (Argentina) \/ Disney+ (Sudam\u00e9rica) \/ DAZN (Espa\u00f1a) \/ Apple TV (EEUU) \/ F1TV<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1, tras haber sido eliminado en la Q2. Despu\u00e9s de los entrenamientos del viernes, cierra el s\u00e1bado con con una actuaci\u00f3n algo irregular. El argentino hab\u00eda [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":223220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[28],"tags":[],"class_list":["post-223219","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1 - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1 - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-18T20:09:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/colapinto-belgica.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1\",\"datePublished\":\"2026-07-18T20:09:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/\"},\"wordCount\":571,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/colapinto-belgica.webp\",\"articleSection\":[\"DEPORTES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/\",\"name\":\"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1 - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/colapinto-belgica.webp\",\"datePublished\":\"2026-07-18T20:09:38+00:00\",\"description\":\"El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/colapinto-belgica.webp\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/colapinto-belgica.webp\",\"width\":790,\"height\":444},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Infinita-Goya-100063870918311\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1 - Radio Infinita Goya","description":"El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/","og_locale":"es_ES","og_type":"article","og_title":"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1 - Radio Infinita Goya","og_description":"El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-07-18T20:09:38+00:00","og_image":[{"width":790,"height":444,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/colapinto-belgica.webp","type":"image\/webp"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1","datePublished":"2026-07-18T20:09:38+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/"},"wordCount":571,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/colapinto-belgica.webp","articleSection":["DEPORTES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/","name":"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1 - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/colapinto-belgica.webp","datePublished":"2026-07-18T20:09:38+00:00","description":"El argentino logr\u00f3 escalar posiciones gracias a las sanciones impuestas a Lando Norris e Isaack Hadjar. Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/colapinto-belgica.webp","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/colapinto-belgica.webp","width":790,"height":444},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/franco-colapinto-largara-11-en-el-gran-premio-de-belgica-de-la-formula-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"Franco Colapinto largar\u00e1 11\u00b0 en el Gran Premio de B\u00e9lgica de la F\u00f3rmula 1"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/223219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=223219"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/223219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/223220"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=223219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=223219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=223219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}