{"id":223230,"date":"2026-07-18T17:36:08","date_gmt":"2026-07-18T20:36:08","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=223230"},"modified":"2026-07-18T17:36:08","modified_gmt":"2026-07-18T20:36:08","slug":"el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/","title":{"rendered":"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero"},"content":{"rendered":"<p>Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029<\/p>\n<p>Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La lectura de los analistas sobre los USD 1.380 millones que faltan<\/p>\n<p>El ministro de Econom\u00eda, Luis Caputo, super\u00f3 en la semana el primer test del programa financiero para 2026 con la colocaci\u00f3n del Bonar 2029 (AO29), con el que el Gobierno ya consigui\u00f3 USD 620 millones que ir\u00e1n a la cuenta del Tesoro y har\u00e1n que los dep\u00f3sitos oficiales en el Banco Central en moneda extranjera suban hasta cerca de USD 4.000 millones. Pero el monto de ofertas que recibi\u00f3 y lo que decidi\u00f3 capturar revela a los analistas del mercado si se van a lograr con facilidad los USD 1.380 millones que faltan para alcanzar el cupo m\u00e1ximo y a qu\u00e9 tasa<\/p>\n<p>La Secretar\u00eda de Finanzas adjudic\u00f3 USD 150 millones en la segunda vuelta de la licitaci\u00f3n, que se suman a los USD 470 millones de la jornada anterior, ambas a una Tasa Nominal Anual (TNA) de 7,99%. En la segunda vuelta, Finanzas recibi\u00f3 ofertas por USD 276 millones. El d\u00eda previo, el Gobierno recibi\u00f3 propuestas por USD 985 millones, lo que implic\u00f3 dejar afuera a m\u00e1s de la mitad de los interesados en el debut del AO29.<\/p>\n<p>Lo que expuso que el equipo econ\u00f3mico prioriz\u00f3 el costo de financiamiento y no la cantidad colocada. La estrategia oficial busc\u00f3 mantener la tasa por debajo del 8% anual, valor considerado por funcionarios como inferior al que exigir\u00eda una colocaci\u00f3n en el mercado internacional.<\/p>\n<p>En la conferencia de prensa, el secretario de Finanzas, Federico Furiase, explic\u00f3 que en la primera licitaci\u00f3n del AO29 no habr\u00eda tope de colocaci\u00f3n a diferencia del Bonar 2027 (AO27) y el Bonar 2028 (AO28), que tuvieron l\u00edmites estrictos en ambas rondas. Pretend\u00edan no aplicar ese l\u00edmite inicial para aprovechar la mayor liquidez que dej\u00f3 el pago de USD 4.200 millones del vencimiento de la semana anterior.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-223232\" src=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1-600x400.jpg 600w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1-150x100.jpg 150w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1-768x512.jpg 768w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1-630x420.jpg 630w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1-696x464.jpg 696w, https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/EATKEUKBJNCQNDWT5KHSXPYUNI-1.avif 992w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Seg\u00fan el \u00faltimo informe diario del Banco Central de la Rep\u00fablica Argentina, al 14 de julio, los dep\u00f3sitos oficiales sumaban USD 3.308 millones.<\/p>\n<p>Con la acreditaci\u00f3n de los fondos del AO29, ese saldo subir\u00e1 a USD 3.928 millones, siempre que no se produzcan nuevos egresos. De esta manera, la colocaci\u00f3n fortalece la posici\u00f3n de liquidez en d\u00f3lares del Tesoro y la capacidad de enfrentar los compromisos detallados en el programa financiero.<\/p>\n<p>Lo que falta<br \/>\nLa operaci\u00f3n dej\u00f3 un saldo concreto para la estrategia oficial: Econom\u00eda necesita captar USD 1.380 millones m\u00e1s para completar el cupo de USD 2.000 millones previsto para este a\u00f1o (USD 6.000 millones).<\/p>\n<p>La pr\u00f3xima licitaci\u00f3n ser\u00e1 en 15 d\u00edas y, seg\u00fan pudo saber Infobae por fuentes del Ministerio de Econom\u00eda, volver\u00e1n los l\u00edmites tradicionales: USD 150 millones en la primera vuelta y USD 100 millones en la segunda. Este esquema retoma la mec\u00e1nica de licitaciones previas, como las del AO27 y AO28, donde los topes por ronda marcaron el ritmo de las colocaciones.<\/p>\n<p>El desempe\u00f1o del AO29 gener\u00f3 interpretaciones positivas entre operadores y analistas. Nicol\u00e1s Cappella, Sales Trader de Invertir en Bolsa (IED), sostuvo: \u201cFue una buena licitaci\u00f3n. Junt\u00f3 un 25% de la emisi\u00f3n en una sola licitaci\u00f3n. Tuvo \u00f3rdenes por USD 1.000 millones, por lo que dej\u00f3 el 50% afuera. Hubo inter\u00e9s y priorizaron cortar a una buena tasa en vez de agarrar todo lo que le ofertaron\u201d. Las cifras muestran un inter\u00e9s significativo por parte de los inversores y la capacidad del Gobierno para negociar condiciones favorables en un contexto vol\u00e1til.<\/p>\n<p>Programa financiero 2026<br \/>\nNecesidades y fuentes de financiamiento preivstas por el Gobierno<\/p>\n<p>Ignacio Morales, director de inversiones de Wise Capital, afirm\u00f3: \u201cNuestra lectura es positiva. En la primera licitaci\u00f3n del AO29, el Gobierno coloc\u00f3 USD 620 millones entre la primera y la segunda vuelta, cerca del 30% del programa de hasta USD 2.000 millones previsto para este a\u00f1o. Con un bid to cover de 2,1x en la primera vuelta, opt\u00f3 por priorizar el costo de financiamiento antes que el monto adjudicado: el bono cort\u00f3 a una TIR de 8,3%, un poco por encima del rendimiento del AN29 en el mercado secundario (7,8% anual). Adem\u00e1s, consideramos favorable que, en la segunda vuelta (donde la tasa ya estaba determinada), las ofertas recibidas tambi\u00e9n duplicaran el monto m\u00e1ximo disponible para adjudicar\u201d.<\/p>\n<p>La estrategia del Ministerio de Econom\u00eda tambi\u00e9n apunt\u00f3 a rechazar parte de las ofertas para mantener bajo control la tasa de inter\u00e9s, sin convalidar niveles mayores de financiamiento que encarezcan el costo para el Tesoro. El \u201cbid to cover\u201d de 2,1x reflej\u00f3 que la demanda super\u00f3 de forma amplia al monto finalmente adjudicado, lo que dio margen al Gobierno para definir condiciones en las pr\u00f3ximas licitaciones.<\/p>\n<p>Aunque el AO29 nunca fue un problema, en el mercado sab\u00edan que Caputo no iba a enfrentar mayores dificultades con el nuevo bono en d\u00f3lares. Donde si tienen mayores reparos es con lo que pretende para el pr\u00f3ximo a\u00f1o electoral: conseguir USD 5.000 millones en el mercado de capitales local y que el Tesoro le compra al BCRA USD 4.900 millones. Aunque para ese entonces puede que se habr\u00e1 el port\u00f3n que el equipo econ\u00f3mico espera para salir a colocar al mercado internacional. La semana que pas\u00f3, pese a la expectativa que hab\u00eda, el \u00edndice de riesgo pa\u00eds no logr\u00f3 quebrar los 400 puntos b\u00e1sicos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La lectura de los analistas sobre los USD 1.380 millones que faltan El ministro de Econom\u00eda, Luis Caputo, super\u00f3 en la semana el primer test del programa financiero [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":223231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[34],"tags":[],"class_list":["post-223230","post","type-post","status-publish","format-standard","has-post-thumbnail","category-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-18T20:36:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/KbAjE_UH.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero\",\"datePublished\":\"2026-07-18T20:36:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/\"},\"wordCount\":928,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/KbAjE_UH.jpg\",\"articleSection\":[\"PRINCIPAL\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/\",\"name\":\"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/KbAjE_UH.jpg\",\"datePublished\":\"2026-07-18T20:36:08+00:00\",\"description\":\"Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/KbAjE_UH.jpg\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/KbAjE_UH.jpg\",\"width\":680,\"height\":383},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/07\\\/18\\\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Infinita-Goya-100063870918311\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero - Radio Infinita Goya","description":"Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/","og_locale":"es_ES","og_type":"article","og_title":"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero - Radio Infinita Goya","og_description":"Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-07-18T20:36:08+00:00","og_image":[{"width":680,"height":383,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/KbAjE_UH.jpg","type":"image\/jpeg"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero","datePublished":"2026-07-18T20:36:08+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/"},"wordCount":928,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/KbAjE_UH.jpg","articleSection":["PRINCIPAL"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/","name":"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/KbAjE_UH.jpg","datePublished":"2026-07-18T20:36:08+00:00","description":"Qu\u00e9 revel\u00f3 para el mercado la emisi\u00f3n del Bonar 2029 Caputo acept\u00f3 USD 620 millones a una tasa inferior a la de una salida al mercado internacional. La","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/KbAjE_UH.jpg","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/07\/KbAjE_UH.jpg","width":680,"height":383},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/07\/18\/el-ministro-de-economia-luis-caputo-supero-el-primer-test-del-nuevo-programa-financiero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"El ministro de Econom\u00eda, Luis Caputo super\u00f3 el primer test del nuevo programa financiero"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/223230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=223230"}],"version-history":[{"count":0,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/223230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/223231"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=223230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=223230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=223230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}