{"id":226580,"date":"2026-09-02T15:59:04","date_gmt":"2026-09-02T18:59:04","guid":{"rendered":"https:\/\/radioinfinitagoya.com.ar\/v1\/?p=226580"},"modified":"2026-09-02T15:59:04","modified_gmt":"2026-09-02T18:59:04","slug":"mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares","status":"publish","type":"post","link":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/","title":{"rendered":"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares"},"content":{"rendered":"<p>M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la capital correntina. Las actividades se desarrollar\u00e1n desde las 11 en el Centro de Educaci\u00f3n F\u00edsica CEF N\u00b0 17 y las disciplinas en competencia ser\u00e1n atletismo convencional, atletismo adaptado, b\u00e1squet 3&#215;3, nataci\u00f3n, triatl\u00f3n y nataci\u00f3n adaptada entre otras.<\/p>\n<p>Los estudiantes llegan al provincial luego de haber superado las etapas local y zonal, representando a sus respectivas instituciones y localidades. En esta oportunidad los competidores buscar\u00e1n alcanzar la clasificaci\u00f3n que les permita representar a Corrientes en los Juegos Deportivos Nacionales Evita.<\/p>\n<p>Durante las jornadas habr\u00e1 competencias en diferentes disciplinas deportivas escolares, entre ellas atletismo convencional, atletismo adaptado, b\u00e1squet 3&#215;3, nataci\u00f3n, triatl\u00f3n y nataci\u00f3n adaptada.<\/p>\n<p>Adem\u00e1s tendr\u00e1n lugar destacado los deportes adaptados con competencias de boccia, tenis de mesa, b\u00e1squet en silla de ruedas, v\u00f3ley sentado y powerlifting, promoviendo la inclusi\u00f3n, la participaci\u00f3n y la igualdad de oportunidades a trav\u00e9s del deporte.<\/p>\n<p>Esta instancia es el resultado del trabajo y el esfuerzo realizado por estudiantes, docentes, entrenadores e instituciones deportivas y educativas a lo largo de todo el proceso clasificatorio.<\/p>\n<p>En estas dos jornadas Corrientes Capital ser\u00e1 escenario de una verdadera fiesta del deporte escolar, donde cientos de alumnos tendr\u00e1n la oportunidad de compartir, competir y representar con orgullo a sus comunidades, persiguiendo el sue\u00f1o de llegar a la instancia nacional.<\/p>\n<p>M\u00e1s de 500 deportistas, seis zonas, m\u00faltiples disciplinas y un mismo objetivo: representar a Corrientes ante el pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la capital correntina. Las actividades se desarrollar\u00e1n desde las 11 en el Centro de Educaci\u00f3n F\u00edsica CEF N\u00b0 17 y las disciplinas en competencia ser\u00e1n atletismo convencional, atletismo adaptado, b\u00e1squet 3&#215;3, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":226581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[26],"tags":[],"class_list":["post-226580","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares - Radio Infinita Goya<\/title>\n<meta name=\"description\" content=\"M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares - Radio Infinita Goya\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Infinita Goya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T18:59:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/09\/imagen-111997.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1058\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Mi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Mi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/\"},\"author\":{\"name\":\"Jorge Mi\u00f1o\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\"},\"headline\":\"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares\",\"datePublished\":\"2026-09-02T18:59:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/imagen-111997.jpg\",\"articleSection\":[\"PROVINCIALES\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/\",\"name\":\"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares - Radio Infinita Goya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/imagen-111997.jpg\",\"datePublished\":\"2026-09-02T18:59:04+00:00\",\"description\":\"M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/imagen-111997.jpg\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/imagen-111997.jpg\",\"width\":1058,\"height\":794},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/2026\\\/09\\\/02\\\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#website\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"name\":\"radioinfinitagoya.com.ar\",\"description\":\"Radio de noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#organization\",\"name\":\"Radio Infinita Goya\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"contentUrl\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-pie-web.png\",\"width\":635,\"height\":326,\"caption\":\"Radio Infinita Goya\"},\"image\":{\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Infinita-Goya-100063870918311\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioinfinitagoya.com.ar\\\/v1\\\/#\\\/schema\\\/person\\\/d4cf9c413d4f6edb24aabdccab49ca4a\",\"name\":\"Jorge Mi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g\",\"caption\":\"Jorge Mi\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/radioinfinitagoya.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares - Radio Infinita Goya","description":"M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares - Radio Infinita Goya","og_description":"M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la","og_url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/","og_site_name":"Radio Infinita Goya","article_publisher":"https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/","article_published_time":"2026-09-02T18:59:04+00:00","og_image":[{"width":1058,"height":794,"url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/09\/imagen-111997.jpg","type":"image\/jpeg"}],"author":"Jorge Mi\u00f1o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Mi\u00f1o","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#article","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/"},"author":{"name":"Jorge Mi\u00f1o","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a"},"headline":"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares","datePublished":"2026-09-02T18:59:04+00:00","mainEntityOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/09\/imagen-111997.jpg","articleSection":["PROVINCIALES"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/","name":"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares - Radio Infinita Goya","isPartOf":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#primaryimage"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#primaryimage"},"thumbnailUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/09\/imagen-111997.jpg","datePublished":"2026-09-02T18:59:04+00:00","description":"M\u00e1s de 500 deportistas escolares participar\u00e1n de la instancia provincial de los Torneos Interescolares que se realizar\u00e1n el 4 y 5 de septiembre en la","breadcrumb":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#primaryimage","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/09\/imagen-111997.jpg","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2026\/09\/imagen-111997.jpg","width":1058,"height":794},{"@type":"BreadcrumbList","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/2026\/09\/02\/mas-de-500-estudiantes-correntinos-competiran-en-los-torneos-interescolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioinfinitagoya.com.ar\/v1\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 500 estudiantes correntinos competir\u00e1n en los Torneos Interescolares"}]},{"@type":"WebSite","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#website","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","name":"radioinfinitagoya.com.ar","description":"Radio de noticias","publisher":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioinfinitagoya.com.ar\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#organization","name":"Radio Infinita Goya","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","contentUrl":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-content\/uploads\/2019\/11\/logo-pie-web.png","width":635,"height":326,"caption":"Radio Infinita Goya"},"image":{"@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Infinita-Goya-100063870918311\/"]},{"@type":"Person","@id":"https:\/\/radioinfinitagoya.com.ar\/v1\/#\/schema\/person\/d4cf9c413d4f6edb24aabdccab49ca4a","name":"Jorge Mi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/910fcf6728fe95320e07a6643c1581fec1c7fc4bf8ae12e3d8f0d0373dc844be?s=96&d=mm&r=g","caption":"Jorge Mi\u00f1o"},"sameAs":["http:\/\/radioinfinitagoya.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/226580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/comments?post=226580"}],"version-history":[{"count":1,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/226580\/revisions"}],"predecessor-version":[{"id":226582,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/posts\/226580\/revisions\/226582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media\/226581"}],"wp:attachment":[{"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/media?parent=226580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/categories?post=226580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioinfinitagoya.com.ar\/v1\/wp-json\/wp\/v2\/tags?post=226580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}